{"id":511,"date":"2016-01-25T10:00:00","date_gmt":"2016-01-25T10:00:00","guid":{"rendered":"https:\/\/new.mariam.org\/blog\/2016\/01\/25\/de-la-faiblesse-a-la-force-de-saul-a-paul\/"},"modified":"2022-03-03T20:00:28","modified_gmt":"2022-03-03T18:00:28","slug":"de-la-faiblesse-a-la-force-de-saul-a-paul","status":"publish","type":"post","link":"https:\/\/mariam.org\/ar\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/","title":{"rendered":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb"},"content":{"rendered":"\n<p>Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible\u2026<br>Pourquoi l\u2019homme arrive-t-il \u00e0 cette situation de violence, d\u2019agression, d\u2019animosit\u00e9 m\u00eame, vis-\u00e0-vis de l\u2019autre ? Ces situations ne se retrouvent-elles pas, h\u00e9las, en nous et autour de nous: Que de souffrances, de violences dans les familles\u2026d\u2019infid\u00e9lit\u00e9s dans le couple et qui augmentent de plus en plus\u2026d\u2019enfants, que personne n\u2019\u00e9coute ou qui souffrent sans que personne ne s\u2019en rende compte\u2026 D\u2019o\u00f9 viennent tous ces comportements ? On ne peut trouver la solution, le rem\u00e8de, qu\u2019en allant \u00e0 la d\u00e9couverte de la source, de la blessure \u00e0 l\u2019int\u00e9rieur de l\u2019homme.<\/p>\n\n\n\n<p>De cet int\u00e9rieur, sort toute m\u00e9chancet\u00e9. O\u00f9 en est la source ? O\u00f9 se trouvent les blessures qui les engendrent?<\/p>\n\n\n\n<p>De cet int\u00e9rieur, sort toute m\u00e9chancet\u00e9. O\u00f9 en est la source ? O\u00f9 se trouvent les blessures qui les engendrent?<\/p>\n\n\n\n<p>Il y a en nous trois dimensions : le corps, l\u2019\u00e2me et l\u2019esprit.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Le corps. C\u2019est la dimension \u00ab mat\u00e9rielle \u00bb. Ce sont nos membres, ces mati\u00e8res chimiques rassembl\u00e9es et qui ont leurs r\u00e9actions, interactions int\u00e9rieures, m\u00eame au niveau hormonal. C\u2019est une masse, un agglom\u00e9rat \u00ab physique, mat\u00e9riel \u00bb.<\/li><li>L\u2019autre dimension est l\u2019\u00e2me, le \u00ab nefesh \u00bb (mot qui vient de respiration). Ce qui distingue l\u2019homme de l\u2019objet, c\u2019est qu\u2019il est vivant, il respire et quand il ne respire plus, il meurt.<br>L\u2019\u00e2me est la dimension vitale, vivante de l\u2019homme. C\u2019est la psych\u00e9, de laquelle vient le mot psychologie.<br>Elle est form\u00e9e de trois composantes ou facult\u00e9s, qui sont tr\u00e8s reli\u00e9es entre elles et aux cellules du cerveau et le cerveau au corps ; car l\u2019homme est une unit\u00e9 compl\u00e8te.<br>Ces facult\u00e9s de l\u2019\u00e2me sont:<br>A &#8211; L\u2019affectivit\u00e9 : L\u2019homme vivant aime ou d\u00e9teste.<br>B &#8211; La rationalit\u00e9. L\u2019homme poss\u00e8de la capacit\u00e9 de r\u00e9fl\u00e9chir avec logique ; il rationalise, il explique les ph\u00e9nom\u00e8nes, il les relie d\u2019une fa\u00e7on logique, scientifique.<br>C &#8211; La volont\u00e9. C\u2019est la force dans l\u2019homme qui le pousse \u00e0 agir ; il a une volont\u00e9, parce qu\u2019il a une libert\u00e9 de choisir. Des fois cette volont\u00e9 agit d\u2019une fa\u00e7on impr\u00e9visible, spontan\u00e9e.<\/li><li>L\u2019esprit est une dimension tr\u00e8s importante.<br>Dans la Bible, quand on parle du c\u0153ur de l\u2019homme on ne vise pas son affectivit\u00e9, mais son esprit, son essence, son centre.<br>Les P\u00e8res de l\u2019Eglise disent que c\u2019est l\u00e0 o\u00f9 l\u2019homme se voit comme unit\u00e9, noyau ; c\u2019est l\u2019endroit qui est reli\u00e9 \u00e0 l\u2019Esprit Saint, \u00e0 Dieu. C\u2019est l\u00e0 o\u00f9 r\u00e9side le libre arbitre, et c\u2019est l\u00e0 aussi o\u00f9 l\u2019homme se pose les questions existentielles : Qui suis-je ? D\u2019o\u00f9 je viens et o\u00f9 je vais ? Quel est mon r\u00f4le ? Qui m\u2019aime ? Par cons\u00e9quent, c\u2019est le lieu o\u00f9 le diable essaie de travailler et d\u2019influencer par des impressions portant l\u2019homme \u00e0 croire qu\u2019il n\u2019est pas aim\u00e9 de Dieu. C\u2019est aussi dans le c\u0153ur que l\u2019homme cherche une assurance plus spirituelle que mat\u00e9rielle.<br>Quand j\u2019enl\u00e8ve tous les d\u00e9tails secondaires de mon JE, il reste ce noyau qui coordonne, rassemble le tout et qui est pr\u00e9sent en force en moi.<br>Le corps, c\u2019est le \u00ab contenant \u00bb o\u00f9 l\u2019\u00e2me exerce son activit\u00e9 humaine. Une activit\u00e9 qui est le fruit de l\u2019interaction entre l\u2019affectivit\u00e9, la raison et la volont\u00e9.<\/li><\/ol>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/i0.wp.com\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul-2.jpg?resize=250%2C300&#038;ssl=1\" alt=\"\" class=\"wp-image-510\"\/><\/figure><\/div>\n\n\n\n<p>Le moteur, le dynamiseur de ces trois facult\u00e9s est l\u2019affectivit\u00e9. M\u00eame quand certaines personnes \u00ab g\u00e8lent \u00bb leur affectivit\u00e9, en \u00ab la mettant au cong\u00e9lateur \u00bb, la raison est influenc\u00e9e par elle, elle devient dure et pas du tout flexible.<br>L\u2019homme est un ensemble de besoins affectifs et non seulement de raison : le besoin est toujours dans l\u2019affectivit\u00e9.<br>Le mouvement de la volont\u00e9 est le r\u00e9sultat de cette concordance entre la raison et l\u2019affectivit\u00e9. Quand la t\u00eate, la raison et l\u2019affectivit\u00e9 s\u2019accordent entre elles, dans le m\u00eame but, la volont\u00e9 bouge. Quand elles ne sont pas en accord, la volont\u00e9 se paralyse. L\u2019homme \u00e9volue toute sa vie entre ces 3 dimensions.<\/p>\n\n\n\n<p>Passons maintenant \u00e0 l\u2019\u00e9volution de l\u2019homme et aux \u00e9tapes de sa croissance.<br>A la naissance, il est un JE tout puissant, illimit\u00e9. Je suis en relation avec moi-m\u00eame, le monde entier est MOI. Le b\u00e9b\u00e9 na\u00eet avec une relation entre le JE et le JE et il n\u2019\u00e9volue que quand il se rend compte qu\u2019il n\u2019est pas sa m\u00e8re ni son p\u00e8re, ni la t\u00e9tine\u2026 La vie commence \u00e0 casser en nous ce JE tout puissant par la relation \u00e0 un TU qui s\u2019oppose, et cr\u00e9\u00e9 la discontinuit\u00e9 : d\u2019o\u00f9 le choc, le NON ! Psychologiquement, on \u00e9volue, mais le Moi profond, reste \u00e9gocentrique. Exp : J\u2019aimerai bien que mes enfants choisissent le m\u00e9tier dont je r\u00eave. Ainsi, dans la vie, nous essayons et tendons toujours \u00e0 retourner \u00e0 ce JE tout puissant qui n\u2019a pas de fronti\u00e8res, de barri\u00e8res.<\/p>\n\n\n\n<p>Dans la famille, le couple qui ne vit pas de conflits est un couple \u00ab mort \u00bb, parce qu\u2019il est impossible \u00e0 l\u2019homme de r\u00e9fl\u00e9chir avec la m\u00eame logique que la femme, ni que la femme sente comme l\u2019homme. Si dans leur vie, il n\u2019y a pas de conflits et de d\u00e9passement de ces conflits, c\u2019est une situation anormale ; Ou alors chacun a transform\u00e9 l\u2019autre \u00e0 son image\u2026 M\u00eame si avec l\u2019\u00e2ge, on finit par se ressembler, par comprendre plus vite ce que l\u2019autre sent, on n\u2019arrivera jamais \u00e0 penser, \u00e0 sentir exactement comme l\u2019autre. Car, la tendance chez la personne humaine, c\u2019est la fusion : faire l\u2019autre comme moi. A ce moment l\u00e0, quand je dialogue avec lui, quand je l\u2019aime, je suis entrain de m\u2019aimer. J\u2019en fais un satellite qui tourne autour de moi. Il r\u00e9fl\u00e9chit comme moi, d\u00e9cide comme moi. C\u2019est ce qui g\u00e8re parfois tous les m\u00e9canismes de notre vie. Parce que l\u2019homme n\u2019est pas encore sorti de ce mythe narcissique, auquel il essaie toujours de revenir : Je suis le centre du monde, le moi illimit\u00e9. Quand la fusion d\u00e9sir\u00e9e ne se fait pas, elle se transforme en opposition, en combat.<\/p>\n\n\n\n<p>L\u2019\u00e9go\u00efsme vient de l\u2019affectivit\u00e9 qui n\u2019a pas \u00e9volu\u00e9, et la fermeture de l\u2019homme devient une attitude.<br>Quand l\u2019\u00e9go\u00efsme et la fermeture entrent en action, ils engendrent la mort et pas seulement avec les armes mais surtout en annulant l\u2019autre comme \u00ab autre \u00bb.<\/p>\n\n\n\n<p>Quant aux relations, l\u2019homme en a \u00e0 trois \u00e0 trois niveaux diff\u00e9rents :<br>1) Une relation avec le pouvoir, le responsable, qui \u00e0 l\u2019extr\u00eame est la relation avec Dieu.<br>2) Une relation avec les autres, avec les pairs, les coll\u00e8gues.<br>3) Et une relation avec les choses, l\u2019argent\u2026<\/p>\n\n\n\n<p>&#8211; Avec le pouvoir, l\u2019homme essaie d\u2019amener \u00e0 lui l\u2019autorit\u00e9 par la soumission, pour qu\u2019elle soit toujours satisfaite de lui. Il lui fait toujours ce qu\u2019elle veut. Avec Dieu, c\u2019est la religiosit\u00e9 naturelle, \u00e0 qui l\u2019homme offre des sacrifices pour le solliciter ou l\u2019apaiser. Et quand \u00e7a ne r\u00e9ussit pas il a le sentiment de culpabilit\u00e9 qui engendre l\u2019effort.<\/p>\n\n\n\n<p>&#8211; Vis \u00e0 vis des pairs, il veut que les autres tiennent compte de lui, \u00eatre leur centre : c\u2019est la domination. Et quand il n\u2019arrive pas \u00e0 y parvenir, il vit le sens d\u2019inf\u00e9riorit\u00e9 qui engendre la violence.<\/p>\n\n\n\n<p>&#8211; Quand l\u2019homme est encore egocentrique, il a une relation de possession avec les choses, c\u2019est la concupiscence : il d\u00e9sire tout poss\u00e9der par n\u2019importe quelle mani\u00e8re et \u00e0 n\u2019importe quel prix. S\u2019il n\u2019arrive pas \u00e0 les poss\u00e9der, il se sent frustr\u00e9. La frustration engendre la cupidit\u00e9.<br>Quand l\u2019homme s\u2019aime soi-m\u00eame, il essaie d\u2019\u00eatre un JE fort par lui-m\u00eame.<br>Le sommet de ce m\u00e9canisme : \u00ab je suis autosuffisant, je n\u2019ai besoin de personne, tous ont besoin de moi, personne ne comprend comme moi, Moi seul j\u2019ai la v\u00e9rit\u00e9. Personne d\u2019autre que moi ne m\u00e9rite qu\u2019on travaille pour lui \u00bb. Et l\u00e0 c\u2019est la mort, la solitude, la m\u00e9galomanie \u00ab massacrante \u00bb : c\u2019est l\u00e0 o\u00f9 l\u2019homme \u00ab nage dans son n\u00e9ant\u00bb\u2026<br>D\u2019un autre c\u00f4t\u00e9, quand l\u2019homme rencontre des obstacles \u00e0 sa toute-puissance, il tombe dans la culpabilit\u00e9, le sens d\u2019inf\u00e9riorit\u00e9 et la frustration : c\u2019est la MORT.<br>Qui peut casser ce maillon de la cha\u00eene du JE qui est un circuit de mort ? Car, dans les 3 situations pr\u00e9c\u00e9dentes, ce maillon du JE ne peut se briser qu\u2019en acceptant un TU qui restera toujours un TU, sans faire peur au JE. Un TU qui ne fera pas peur, c\u2019est l\u2019image du Christ dans la cr\u00e8che : un b\u00e9b\u00e9 sans d\u00e9fense.<br>Quand l\u2019autre vient dans ma vie et que je d\u00e9couvre qu\u2019il m\u2019aime gratuitement sans rien m\u2019enlever, il ne me fait pas peur. A ce moment-l\u00e0, le TU devient parfois plus important que le JE.<br>Toute la Foi, la vie chr\u00e9tienne est bas\u00e9e sur cette r\u00e9alit\u00e9 : il y a quelqu\u2019UN qui m\u2019aime gratuitement et sans condition, comme je suis, c\u2019est pourquoi je deviens fort dans ma faiblesse. Si mon affectivit\u00e9 r\u00e9agit avec Lui et si je reconnais que j\u2019ai besoin de Son amour qui est gratuit, je suis toujours faible mais fort dans Son amour.<br>Je reste toujours le m\u00eame : un homme de besoins. Mais quand je d\u00e9couvre qu\u2019Il m\u2019aime, je dialogue avec Lui pour trouver la v\u00e9rit\u00e9 et je reconnais que je ne poss\u00e8de pas seule la v\u00e9rit\u00e9, je reconnais que j\u2019ai \u00e0 aimer sans retour.<br>Si l\u2019homme est aim\u00e9, il aime. Comme il est aim\u00e9, il aime et autant qu\u2019il est aim\u00e9 il peut aimer.<\/p>\n\n\n\n<p>C\u2019est l\u2019exp\u00e9rience de (Saul) St Paul que nous trouvons dans le livre des Actes des Ap\u00f4tres au chapitre 9.<br>Saul menace les Chr\u00e9tiens, les tue, (il essaie de plaire au pouvoir).<br>Sur le chemin de Damas, il tombe par terre (Il revient \u00e0 sa faiblesse).<br>Le Seigneur lui dit : \u201cPourquoi me pers\u00e9cutes-tu ?\u201d<br>&#8211; \u201cQui es-tu ?\u201d r\u00e9pondit-il.<\/p>\n\n\n\n<p>Saul voulait tuer l\u2019autre pour plaire \u00e0 Dieu. Dieu vient lui dire \u00ab Je suis l\u2019autre et chaque fois que tu annules l\u2019autre de ta vie, tu m\u2019annules \u00e0 moi, tu ME tues \u00bb.<br>Par la pr\u00e9sence de l\u2019autre dans notre vie, nous ne devenons plus le centre, notre logique n\u2019est plus LA logique, LE principe\u2026<br>Saul s\u2019est lev\u00e9 et il ne voyait plus (il s\u2019agit de la vue int\u00e9rieure du c\u0153ur). Il ne comprenait plus pourquoi il existait. Il est rest\u00e9 3 jours comme mort, il a re\u00e7u un choc : un NON \u00e0 son JE.<\/p>\n\n\n\n<p>Ananie que Dieu envoie vers Saul n\u2019arrivait pas \u00e0 comprendre, \u00e0 croire ce que l\u2019amour gratuit peut faire de cet homme : un disciple !<\/p>\n\n\n\n<p>Quand on fait soi-m\u00eame l\u2019exp\u00e9rience de cet amour, on peut alors croire ce qu\u2019il est capable de faire dans les autres, m\u00eame les \u00ab m\u00e9chants \u00bb\u2026 Et quand nous d\u00e9couvrons \u00ab la paternit\u00e9 \u00bb, nous sommes capables alors de croire \u00e0 la \u00ab fraternit\u00e9 \u00bb. Les autres deviennent nos fr\u00e8res. Quand nous dialoguons, nous nous ne pouvons que trouver un d\u00e9nominateur commun pour une certaine convivialit\u00e9. Mais pour \u00eatre fr\u00e8res, nous avons \u00e0 d\u00e9couvrir que nous avons le m\u00eame PERE.<\/p>\n\n\n\n<p>St Paul a exp\u00e9riment\u00e9 qu\u2019Il y a quelqu\u2019UN qui l\u2019aime dans sa faiblesse, qui l\u2019aime m\u00eame s\u2019il lui fait du tort, qui l\u2019aime sans retour et sans menace. Paul a compris \u00e0 ce moment qui il \u00e9tait, lui ; qui est Dieu, et qui est l\u2019autre. Dieu est un P\u00e8re qui l\u2019aime gratuitement ; les autres sont ses fr\u00e8res. Et donc, lui-m\u00eame est un fils aim\u00e9 gratuitement et sans aucune condition : \u00ab un p\u00e9cheur que Dieu a regard\u00e9 avec une mis\u00e9ricorde infinie \u00bb.<\/p>\n\n\n\n<p>(<em>Transcription et traduction : Sr Marcelle KARAM.<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible<\/p>\n","protected":false},"author":1,"featured_media":509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"nf_dc_page":"","footnotes":""},"categories":[15],"tags":[205,204,207,206,202,203,200,201,199],"class_list":["post-511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meditations-et-homelies","tag-ame","tag-coeur","tag-conversion","tag-esprit","tag-faiblesse","tag-force","tag-paul","tag-ramzi-jreige","tag-saul"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org<\/title>\n<meta name=\"description\" content=\"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mariam.org\/ar\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org\" \/>\n<meta property=\"og:description\" content=\"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mariam.org\/ar\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/\" \/>\n<meta property=\"og:site_name\" content=\"mariam.org\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/mariam.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-25T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T18:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariam.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mariam_org\" \/>\n<meta name=\"twitter:site\" content=\"@mariam_org\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariam.org\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/\"},\"author\":{\"name\":\"mariam.org\",\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#\\\/schema\\\/person\\\/c6574796fa42bdd3d3aadfc1102d76d4\"},\"headline\":\"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb\",\"datePublished\":\"2016-01-25T10:00:00+00:00\",\"dateModified\":\"2022-03-03T18:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/\"},\"wordCount\":2119,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mariam.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1\",\"keywords\":[\"\u00e2me\",\"coeur\",\"Conversion\",\"esprit\",\"faiblesse\",\"force\",\"Paul\",\"Ramzi Jreige\",\"Saul\"],\"articleSection\":[\"\u062a\u0623\u0645\u0644\u0627\u062a \u0648\u0639\u0638\u0627\u062a\"],\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/\",\"url\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/\",\"name\":\"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mariam.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1\",\"datePublished\":\"2016-01-25T10:00:00+00:00\",\"dateModified\":\"2022-03-03T18:00:28+00:00\",\"description\":\"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mariam.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mariam.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1\",\"width\":250,\"height\":318,\"caption\":\"P. Ramzi jreige cm.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mariam.org\\\/meditations\\\/meditations-et-homelies\\\/de-la-faiblesse-a-la-force-de-saul-a-paul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0651\u0629\",\"item\":\"https:\\\/\\\/mariam.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#website\",\"url\":\"http:\\\/\\\/mariam.org\\\/ar\\\/\",\"name\":\"mariam.org\",\"description\":\"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0628\u0627\u0632\u064a\u0644\u064a\u0643 \u0633\u064a\u062f\u0629 \u0627\u0644\u0623\u064a\u0642\u0648\u0646\u0629 \u0627\u0644\u0639\u062c\u0627\u0626\u0628\u064a\u0629 \u0644\u0644\u0622\u0628\u0627\u0621 \u0627\u0644\u0644\u0639\u0627\u0632\u0631\u064a\u064a\u0646 - \u0627\u0644\u0623\u0634\u0631\u0641\u064a\u0629\",\"publisher\":{\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/mariam.org\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#organization\",\"name\":\"mariam.org\",\"url\":\"http:\\\/\\\/mariam.org\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/wp.mariam.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-cropped-524638_553054238072997_864065168_n-e1641636108655.jpg?fit=100%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/wp.mariam.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-cropped-524638_553054238072997_864065168_n-e1641636108655.jpg?fit=100%2C100&ssl=1\",\"width\":100,\"height\":100,\"caption\":\"mariam.org\"},\"image\":{\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/mariam.org\",\"https:\\\/\\\/x.com\\\/mariam_org\",\"http:\\\/\\\/instagram.com\\\/mariam_org\",\"http:\\\/\\\/www.youtube.com\\\/channel\\\/UCxEUh-2yAEfdGIxl_TUoKuA?sub_confirmation=1\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/mariam.org\\\/ar\\\/#\\\/schema\\\/person\\\/c6574796fa42bdd3d3aadfc1102d76d4\",\"name\":\"mariam.org\",\"sameAs\":[\"https:\\\/\\\/mariam.org\"],\"url\":\"https:\\\/\\\/mariam.org\\\/ar\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org","description":"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mariam.org\/ar\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/","og_locale":"ar_AR","og_type":"article","og_title":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org","og_description":"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible","og_url":"https:\/\/mariam.org\/ar\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/","og_site_name":"mariam.org","article_publisher":"http:\/\/www.facebook.com\/mariam.org","article_published_time":"2016-01-25T10:00:00+00:00","article_modified_time":"2022-03-03T18:00:28+00:00","og_image":[{"width":250,"height":318,"url":"https:\/\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg","type":"image\/jpeg"}],"author":"mariam.org","twitter_card":"summary_large_image","twitter_creator":"@mariam_org","twitter_site":"@mariam_org","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"mariam.org","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"14 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#article","isPartOf":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/"},"author":{"name":"mariam.org","@id":"http:\/\/mariam.org\/ar\/#\/schema\/person\/c6574796fa42bdd3d3aadfc1102d76d4"},"headline":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb","datePublished":"2016-01-25T10:00:00+00:00","dateModified":"2022-03-03T18:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/"},"wordCount":2119,"commentCount":0,"publisher":{"@id":"http:\/\/mariam.org\/ar\/#organization"},"image":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1","keywords":["\u00e2me","coeur","Conversion","esprit","faiblesse","force","Paul","Ramzi Jreige","Saul"],"articleSection":["\u062a\u0623\u0645\u0644\u0627\u062a \u0648\u0639\u0638\u0627\u062a"],"inLanguage":"ar","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/","url":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/","name":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb - mariam.org","isPartOf":{"@id":"http:\/\/mariam.org\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#primaryimage"},"image":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1","datePublished":"2016-01-25T10:00:00+00:00","dateModified":"2022-03-03T18:00:28+00:00","description":"Aujourd\u2019hui, ce que nous vivons dans la r\u00e9gion n\u2019est pas nouveau : on prend des otages pour gagner de l\u2019argent, on d\u00e9capite, le fort l\u2019emporte sur le faible","breadcrumb":{"@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#primaryimage","url":"https:\/\/i0.wp.com\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mariam.org\/wp-content\/uploads\/2016\/01\/de-la-faiblesse-a-la-force-de-saul-a-paul.jpg?fit=250%2C318&ssl=1","width":250,"height":318,"caption":"P. Ramzi jreige cm."},{"@type":"BreadcrumbList","@id":"https:\/\/mariam.org\/meditations\/meditations-et-homelies\/de-la-faiblesse-a-la-force-de-saul-a-paul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0651\u0629","item":"https:\/\/mariam.org\/"},{"@type":"ListItem","position":2,"name":"\u00abDe la faiblesse \u00e0 la force\u2026 de Saul \u00e0 Paul\u00bb"}]},{"@type":"WebSite","@id":"http:\/\/mariam.org\/ar\/#website","url":"http:\/\/mariam.org\/ar\/","name":"mariam.org","description":"\u0627\u0644\u0645\u0648\u0642\u0639 \u0627\u0644\u0631\u0633\u0645\u064a \u0644\u0628\u0627\u0632\u064a\u0644\u064a\u0643 \u0633\u064a\u062f\u0629 \u0627\u0644\u0623\u064a\u0642\u0648\u0646\u0629 \u0627\u0644\u0639\u062c\u0627\u0626\u0628\u064a\u0629 \u0644\u0644\u0622\u0628\u0627\u0621 \u0627\u0644\u0644\u0639\u0627\u0632\u0631\u064a\u064a\u0646 - \u0627\u0644\u0623\u0634\u0631\u0641\u064a\u0629","publisher":{"@id":"http:\/\/mariam.org\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/mariam.org\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"http:\/\/mariam.org\/ar\/#organization","name":"mariam.org","url":"http:\/\/mariam.org\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/mariam.org\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/wp.mariam.org\/wp-content\/uploads\/2022\/01\/cropped-cropped-524638_553054238072997_864065168_n-e1641636108655.jpg?fit=100%2C100&ssl=1","contentUrl":"https:\/\/i2.wp.com\/wp.mariam.org\/wp-content\/uploads\/2022\/01\/cropped-cropped-524638_553054238072997_864065168_n-e1641636108655.jpg?fit=100%2C100&ssl=1","width":100,"height":100,"caption":"mariam.org"},"image":{"@id":"http:\/\/mariam.org\/ar\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/mariam.org","https:\/\/x.com\/mariam_org","http:\/\/instagram.com\/mariam_org","http:\/\/www.youtube.com\/channel\/UCxEUh-2yAEfdGIxl_TUoKuA?sub_confirmation=1"]},{"@type":"Person","@id":"http:\/\/mariam.org\/ar\/#\/schema\/person\/c6574796fa42bdd3d3aadfc1102d76d4","name":"mariam.org","sameAs":["https:\/\/mariam.org"],"url":"https:\/\/mariam.org\/ar\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/posts\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":7,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/posts\/511\/revisions"}],"predecessor-version":[{"id":2155,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/posts\/511\/revisions\/2155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/media?parent=511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/categories?post=511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariam.org\/ar\/wp-json\/wp\/v2\/tags?post=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}